{"id":100,"date":"2018-08-13T10:13:43","date_gmt":"2018-08-13T10:13:43","guid":{"rendered":"https:\/\/watch-center.eu\/?page_id=100"},"modified":"2024-12-06T19:05:00","modified_gmt":"2024-12-06T18:05:00","slug":"servizi-orologi","status":"publish","type":"page","link":"https:\/\/watch-center.eu\/en\/servizi-orologi","title":{"rendered":"Services"},"content":{"rendered":"<div id=\"pl-100\"  class=\"panel-layout\" ><div id=\"pg-100-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-100-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-100-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h1 style=\"text-align: center;\">SERVIZI DI ASSISTENZA<br \/>\nE RIPARAZIONE OROLOGI<a id=\"servizi\"><\/a><\/h1>\n<hr>\n<p style=\"text-align: center;\">\" L'orologio, non solo uno strumento di misura del tempo ma un gioiello che coniuga l\u2019eleganza di una marca di grande tradizione a prestazioni d\u2019alta tecnologia. Un bene cosi prezioso merita la necessaria cura esclusivamente nei centri specializzati per una idonea assistenza tecnica. Questo perch\u00e9 le dovute attenzioni possono essere poste solo da chi ha scelto questa professione investendo la propria passione nello studio, nell'aggiornamento continuo e nel miglioramento delle attrezzature adottando le adeguate tecnologie \"<\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-100-0-1\"  class=\"panel-grid-cell\" ><div id=\"panel-100-0-1-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277-100\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img \n\tsrc=\"https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/zenith-uomo.jpg\" width=\"1280\" height=\"853\" srcset=\"https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/zenith-uomo.jpg 1280w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/zenith-uomo-300x200.jpg 300w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/zenith-uomo-768x512.jpg 768w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/zenith-uomo-1024x682.jpg 1024w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/zenith-uomo-600x400.jpg 600w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/zenith-uomo-272x182.jpg 272w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" title=\"zenith uomo\" alt=\"zenith uomo\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><\/div><\/div><div id=\"pg-100-1\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-style panel-row-style-for-100-1\" data-stretch-type=\"full\" ><div id=\"pgc-100-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-100-1-0-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"2\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277-100\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img \n\tsrc=\"https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/09\/san-francisco-watchmaker.jpg\" width=\"720\" height=\"960\" srcset=\"https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/09\/san-francisco-watchmaker.jpg 720w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/09\/san-francisco-watchmaker-225x300.jpg 225w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/09\/san-francisco-watchmaker-600x800.jpg 600w\" sizes=\"(max-width: 720px) 100vw, 720px\" title=\"san francisco watchmaker\" alt=\"san francisco watchmaker\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><\/div><div id=\"pgc-100-1-1\"  class=\"panel-grid-cell\" ><div id=\"panel-100-1-1-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"3\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h1><a id=\"chisiamo\"><\/a>CHI SIAMO<\/h1>\n<hr \/>\n<p style=\"text-align: justify;\">Watch Center \u00e8 una azienda artigianale che effettua Servizi di assistenza tecnica, revisione, manutenzione, riparazione e restauro, di ogni tipo di orologio, da quelli da polso e da tasca agli orologi da parete ed a pendolo e soprattutto gli orologi delle grandi maison svizzere e di notevole valore storico ed artistico.<\/p>\n<p style=\"text-align: justify;\">I nostri\u00a0interventi\u00a0sono\u00a0di elevato standard qualitativo\u00a0e svolti\u00a0direttamente nel nostro laboratorio di assistenza tecnica, quindi\u00a0senza intermediari.<br \/>\nQuesto aspetto, oltre alle pi\u00f9 moderne attrezzature richieste dalle grandi maison dell\u2019 alta orologeria, le specializzazioni e l\u2019esperienza accumulata in decenni di attivit\u00e0, ci permette di poter garantire ai nostri Clienti servizi a\u00a0prezzi competitivi\u00a0e la\u00a0garanzia di 24 mesi sulle riparazioni dell\u2019orologio (nel caso di\u00a0Servizio Completo di revisione).<\/p>\n<p style=\"text-align: justify;\">Il nostro impegno e la nostra professionalit\u00e0 ci hanno consentito di consolidare, nel tempo, i rapporti di fiducia con la clientela che si rivolge a noi per intervenire su prestigiosi marchi come: Rolex, Patek Philippe,\u00a0Vacheron Constantin,\u00a0Audemars Piguet, Jaeger LeCoultre,\u00a0\u00a0Cartier,\u00a0Panerai, Zenith, TAG Heuer e molte altre.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-100-2\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-100-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-100-2-0-0\" class=\"so-panel widget widget_black-studio-tinymce widget_black_studio_tinymce panel-first-child panel-last-child\" data-index=\"4\" ><div class=\"textwidget\"><p><iframe loading=\"lazy\" src=\"https:\/\/www.facebook.com\/plugins\/video.php?href=https%3A%2F%2Fwww.facebook.com%2Fpippi.meduri%2Fvideos%2F10218530008832509%2F&show_text=1&width=560\" width=\"560\" height=\"426\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowTransparency=\"true\" allow=\"encrypted-media\" allowFullScreen=\"true\"><\/iframe><\/p>\n<\/div><\/div><\/div><div id=\"pgc-100-2-1\"  class=\"panel-grid-cell\" ><div id=\"panel-100-2-1-0\" class=\"so-panel widget widget_shortcodes-ultimate shortcodes-ultimate panel-first-child panel-last-child\" data-index=\"5\" ><h3 class=\"widget-title\">Instagram<\/h3><div class=\"textwidget\">\t\t<div id=\"instagram-gallery-feed-0\" class=\"instagram-gallery-feed\" data-feed=\"{&quot;id&quot;:0,&quot;account_id&quot;:&quot;8646405122155601&quot;,&quot;source&quot;:&quot;username&quot;,&quot;tag&quot;:&quot;wordpress&quot;,&quot;order_by&quot;:&quot;top_media&quot;,&quot;layout&quot;:&quot;gallery&quot;,&quot;limit&quot;:6,&quot;columns&quot;:3,&quot;spacing&quot;:10,&quot;lazy&quot;:false,&quot;responsive&quot;:{&quot;desktop&quot;:{&quot;columns&quot;:3,&quot;spacing&quot;:10},&quot;tablet&quot;:{&quot;columns&quot;:2,&quot;spacing&quot;:8},&quot;mobile&quot;:{&quot;columns&quot;:1,&quot;spacing&quot;:6},&quot;breakpoints&quot;:{&quot;tablet&quot;:768,&quot;mobile&quot;:480}},&quot;aspect_ratio&quot;:{&quot;width&quot;:1,&quot;height&quot;:1},&quot;highlight&quot;:{&quot;tag&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;position&quot;:&quot;1,3,5&quot;},&quot;reel&quot;:{&quot;hide&quot;:false},&quot;copyright&quot;:{&quot;hide&quot;:false,&quot;placeholder&quot;:&quot;&quot;},&quot;profile&quot;:{&quot;display&quot;:false,&quot;username&quot;:&quot;&quot;,&quot;nickname&quot;:&quot;&quot;,&quot;website&quot;:&quot;&quot;,&quot;biography&quot;:&quot;&quot;,&quot;link_text&quot;:&quot;Follow&quot;,&quot;website_text&quot;:&quot;Website&quot;,&quot;avatar&quot;:&quot;&quot;},&quot;box&quot;:{&quot;display&quot;:false,&quot;padding&quot;:1,&quot;radius&quot;:0,&quot;background&quot;:&quot;#fefefe&quot;,&quot;profile&quot;:false,&quot;desc&quot;:&quot;&quot;,&quot;text_color&quot;:&quot;#000000&quot;},&quot;mask&quot;:{&quot;display&quot;:true,&quot;background&quot;:&quot;#000000&quot;,&quot;icon_color&quot;:&quot;#ffffff&quot;,&quot;likes_count&quot;:true,&quot;comments_count&quot;:true},&quot;card&quot;:{&quot;display&quot;:false,&quot;radius&quot;:1,&quot;font_size&quot;:12,&quot;background&quot;:&quot;#ffffff&quot;,&quot;background_hover&quot;:&quot;&quot;,&quot;text_color&quot;:&quot;#000000&quot;,&quot;padding&quot;:5,&quot;likes_count&quot;:true,&quot;text_length&quot;:10,&quot;comments_count&quot;:true,&quot;text_align&quot;:&quot;left&quot;},&quot;carousel&quot;:{&quot;centered_slides&quot;:false,&quot;autoplay&quot;:false,&quot;autoplay_interval&quot;:3000,&quot;navarrows&quot;:true,&quot;navarrows_color&quot;:&quot;&quot;,&quot;pagination&quot;:true,&quot;pagination_color&quot;:&quot;&quot;},&quot;modal&quot;:{&quot;display&quot;:true,&quot;profile&quot;:true,&quot;media_description&quot;:true,&quot;likes_count&quot;:true,&quot;comments_count&quot;:true,&quot;comments_list&quot;:false,&quot;text_align&quot;:&quot;left&quot;,&quot;modal_align&quot;:&quot;right&quot;,&quot;text_length&quot;:10000,&quot;font_size&quot;:12},&quot;button&quot;:{&quot;display&quot;:true,&quot;text&quot;:&quot;View on Instagram&quot;,&quot;text_color&quot;:&quot;#ffff&quot;,&quot;background&quot;:&quot;&quot;,&quot;background_hover&quot;:&quot;&quot;},&quot;button_load&quot;:{&quot;display&quot;:false,&quot;text&quot;:&quot;Load more...&quot;,&quot;text_color&quot;:&quot;#ffff&quot;,&quot;background&quot;:&quot;&quot;,&quot;background_hover&quot;:&quot;&quot;}}\">\n\t\t<!-- <FeedContainer\/> -->\n\t\t<\/div>\n\t\t<\/div><\/div><\/div><\/div><div id=\"pg-100-3\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-100-3-0\"  class=\"panel-grid-cell\" ><div id=\"panel-100-3-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"6\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h1>ALCUNI INTERVENTI SU OROLOGI:<\/h1>\n<hr \/>\n<p><span style=\"color: #b4946b;\"><i class=\"fa fa-angle-double-right \" ><\/i><\/span> Rolex<\/p>\n<p><span style=\"color: #b4946b;\"><i class=\"fa fa-angle-double-right \" ><\/i><\/span> Patek Philippe<\/p>\n<p><span style=\"color: #b4946b;\"><i class=\"fa fa-angle-double-right \" ><\/i><\/span> Audemars Piguet<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-100-3-1\"  class=\"panel-grid-cell\" ><div id=\"panel-100-3-1-0\" class=\"so-panel widget widget_sow-slider panel-first-child panel-last-child\" data-index=\"7\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-slider so-widget-sow-slider-default-71d5c9d9c341-100\"\n\t\t\t\n\t\t>\t\t\t\t<div class=\"sow-slider-base\" style=\"display: none\" tabindex=\"0\">\n\t\t\t\t\t<ul\n\t\t\t\t\tclass=\"sow-slider-images\"\n\t\t\t\t\tdata-settings=\"{&quot;pagination&quot;:true,&quot;speed&quot;:&quot;800&quot;,&quot;timeout&quot;:&quot;3000&quot;,&quot;paused&quot;:false,&quot;pause_on_hover&quot;:false,&quot;swipe&quot;:&quot;on&quot;,&quot;nav_always_show_desktop&quot;:&quot;&quot;,&quot;nav_always_show_mobile&quot;:&quot;&quot;,&quot;breakpoint&quot;:&quot;780px&quot;,&quot;unmute&quot;:false,&quot;anchor&quot;:null}\"\n\t\t\t\t\t\t\t\t\t\tdata-anchor-id=\"\"\n\t\t\t\t>\t\t<li class=\"sow-slider-image\" style=\"visibility: visible;\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p7.jpg\" class=\"sow-slider-background-image\" alt=\"riparazione rolex p7\" style=\"\" srcset=\"https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p7.jpg 1280w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p7-300x200.jpg 300w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p7-768x512.jpg 768w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p7-1024x682.jpg 1024w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p7-600x400.jpg 600w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p7-272x182.jpg 272w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/>\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image\" style=\"visibility: hidden;\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p6.jpg\" class=\"sow-slider-background-image\" alt=\"riparazione rolex p6\" style=\"\" srcset=\"https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p6.jpg 1280w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p6-300x200.jpg 300w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p6-768x512.jpg 768w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p6-1024x682.jpg 1024w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p6-600x400.jpg 600w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p6-272x182.jpg 272w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/>\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image\" style=\"visibility: hidden;\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p5.jpg\" class=\"sow-slider-background-image\" alt=\"riparazione rolex p5\" style=\"\" srcset=\"https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p5.jpg 1280w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p5-300x200.jpg 300w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p5-768x512.jpg 768w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p5-1024x682.jpg 1024w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p5-600x400.jpg 600w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p5-272x182.jpg 272w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/>\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image\" style=\"visibility: hidden;\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-audemars-p1.jpg\" class=\"sow-slider-background-image\" alt=\"riparazione audemars p1\" style=\"\" srcset=\"https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-audemars-p1.jpg 1280w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-audemars-p1-300x200.jpg 300w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-audemars-p1-768x512.jpg 768w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-audemars-p1-1024x682.jpg 1024w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-audemars-p1-600x400.jpg 600w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-audemars-p1-272x182.jpg 272w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/>\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image\" style=\"visibility: hidden;\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-audemars-p3.jpg\" class=\"sow-slider-background-image\" alt=\"riparazione audemars p3\" style=\"\" srcset=\"https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-audemars-p3.jpg 1280w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-audemars-p3-300x200.jpg 300w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-audemars-p3-768x512.jpg 768w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-audemars-p3-1024x682.jpg 1024w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-audemars-p3-600x400.jpg 600w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-audemars-p3-272x182.jpg 272w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/>\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image\" style=\"visibility: hidden;\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-audemars-p2.jpg\" class=\"sow-slider-background-image\" alt=\"riparazione audemars p2\" style=\"\" srcset=\"https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-audemars-p2.jpg 1280w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-audemars-p2-300x200.jpg 300w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-audemars-p2-768x512.jpg 768w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-audemars-p2-1024x682.jpg 1024w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-audemars-p2-600x400.jpg 600w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-audemars-p2-272x182.jpg 272w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/>\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image\" style=\"visibility: hidden;\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-patek-p1.jpg\" class=\"sow-slider-background-image\" alt=\"riparazione patek p1\" style=\"\" srcset=\"https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-patek-p1.jpg 1280w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-patek-p1-300x200.jpg 300w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-patek-p1-768x512.jpg 768w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-patek-p1-1024x682.jpg 1024w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-patek-p1-600x400.jpg 600w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-patek-p1-272x182.jpg 272w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/>\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image\" style=\"visibility: hidden;\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-patek-p2.jpg\" class=\"sow-slider-background-image\" alt=\"riparazione patek p2\" style=\"\" srcset=\"https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-patek-p2.jpg 1280w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-patek-p2-300x200.jpg 300w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-patek-p2-768x512.jpg 768w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-patek-p2-1024x682.jpg 1024w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-patek-p2-600x400.jpg 600w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-patek-p2-272x182.jpg 272w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/>\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image\" style=\"visibility: hidden;\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p3.jpg\" class=\"sow-slider-background-image\" alt=\"riparazione rolex p3\" style=\"\" srcset=\"https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p3.jpg 1280w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p3-300x200.jpg 300w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p3-768x512.jpg 768w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p3-1024x682.jpg 1024w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p3-600x400.jpg 600w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p3-272x182.jpg 272w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/>\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image\" style=\"visibility: hidden;\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p1.jpg\" class=\"sow-slider-background-image\" alt=\"riparazione rolex p1\" style=\"\" srcset=\"https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p1.jpg 1280w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p1-300x200.jpg 300w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p1-768x512.jpg 768w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p1-1024x682.jpg 1024w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p1-600x400.jpg 600w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p1-272x182.jpg 272w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/>\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image\" style=\"visibility: hidden;\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p2.jpg\" class=\"sow-slider-background-image\" alt=\"riparazione rolex p2\" style=\"\" srcset=\"https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p2.jpg 1280w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p2-300x200.jpg 300w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p2-768x512.jpg 768w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p2-1024x682.jpg 1024w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p2-600x400.jpg 600w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p2-272x182.jpg 272w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/>\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image\" style=\"visibility: hidden;\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p4.jpg\" class=\"sow-slider-background-image\" alt=\"riparazione rolex p4\" style=\"\" srcset=\"https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p4.jpg 1280w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p4-300x200.jpg 300w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p4-768x512.jpg 768w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p4-1024x682.jpg 1024w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p4-600x400.jpg 600w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/riparazione-rolex-p4-272x182.jpg 272w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/>\t\t<\/li>\n\t\t<\/ul>\t\t\t\t<ol class=\"sow-slider-pagination\">\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"0\" aria-label=\"Display slide 1\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"1\" aria-label=\"Display slide 2\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"2\" aria-label=\"Display slide 3\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"3\" aria-label=\"Display slide 4\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"4\" aria-label=\"Display slide 5\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"5\" aria-label=\"Display slide 6\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"6\" aria-label=\"Display slide 7\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"7\" aria-label=\"Display slide 8\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"8\" aria-label=\"Display slide 9\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"9\" aria-label=\"Display slide 10\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"10\" aria-label=\"Display slide 11\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"11\" aria-label=\"Display slide 12\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t<\/ol>\n\n\t\t\t\t<div class=\"sow-slide-nav sow-slide-nav-next\">\n\t\t\t\t\t<a href=\"#\" data-goto=\"next\" aria-label=\"Next slide\" data-action=\"next\">\n\t\t\t\t\t\t<em class=\"sow-sld-icon-thin-right\"><\/em>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"sow-slide-nav sow-slide-nav-prev\">\n\t\t\t\t\t<a href=\"#\" data-goto=\"previous\" aria-label=\"Previous slide\" data-action=\"prev\">\n\t\t\t\t\t\t<em class=\"sow-sld-icon-thin-left\"><\/em>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><\/div><\/div><div id=\"pg-100-4\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-style panel-row-style-for-100-4\" data-stretch-type=\"full\" ><div id=\"pgc-100-4-0\"  class=\"panel-grid-cell\" ><div id=\"panel-100-4-0-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"8\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277-100\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img \n\tsrc=\"https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/09\/Attrezzature-watch-center.jpeg\" width=\"1024\" height=\"911\" srcset=\"https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/09\/Attrezzature-watch-center.jpeg 1024w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/09\/Attrezzature-watch-center-300x267.jpeg 300w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/09\/Attrezzature-watch-center-768x683.jpeg 768w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/09\/Attrezzature-watch-center-600x534.jpeg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" title=\"Attrezzature watch center\" alt=\"Attrezzature watch center\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><\/div><div id=\"pgc-100-4-1\"  class=\"panel-grid-cell\" ><div id=\"panel-100-4-1-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"9\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h1>MANUTENZIONE E REVISIONE<\/h1>\n<hr \/>\n<h2><span style=\"text-decoration: underline;\">La Manutenzione<\/span><\/h2>\n<p><em><span style=\"color: #b4946b;\"><i class=\"fa fa-angle-double-right \" ><\/i>\u00a0\u00a0<\/span>Perch\u00e9 \u00e8 necessario fare una accurata manutenzione dell' orologio?<\/em><\/p>\n<p>La manutenzione deve essere eseguita ogni anno\u00a0(vedi istruzioni della Casa Madre), per prevenire danni ai componenti dell\u2019orologio.Presso il nostro laboratorio \u00e8 svolta in brevissimo tempo e comprende...<a href=\"https:\/\/watch-center.eu\/manutenzione-orologi#manutenzione\" target=\"_blank\" rel=\"noopener\"><em><span style=\"color: #b4946b;\">Leggi tutto<\/span><\/em><\/a><\/p>\n<h2><span style=\"text-decoration: underline;\">La Revisione<\/span><\/h2>\n<p><em><span style=\"color: #b4946b;\"><i class=\"fa fa-angle-double-right \" ><\/i>\u00a0\u00a0<\/span>Perch\u00e9 la revisione?<\/em><\/p>\n<p>Nell'orologio, per ridurre gli attriti tra le varie parti in movimento, vengono introdotti i lubrificanti specifici. Durante la loro vita di 3-5 anni perdono, per usura, la viscosit\u00e0. Quindi la revisione oltre ai tempi consigliati significa...<a href=\"https:\/\/watch-center.eu\/manutenzione-orologi#revisione\" target=\"_blank\" rel=\"noopener\"><em><span style=\"color: #b4946b;\">Leggi tutto<\/span><\/em><\/a><\/p>\n<h2><span style=\"text-decoration: underline;\">L'impermeabilit\u00e0<\/span><\/h2>\n<p><em><span style=\"color: #b4946b;\"><i class=\"fa fa-angle-double-right \" ><\/i>\u00a0\u00a0<\/span>Perch\u00e9 il controllo d'impermeabilit\u00e0?<\/em><\/p>\n<p>L\u2019Impermeabilit\u00e0, protegge il movimento da polvere, umidit\u00e0 e da ogni rischio di deterioramento in caso d\u2019immersione o contatto con l\u2019acqua. L\u2019impermeabilit\u00e0...<a href=\"https:\/\/watch-center.eu\/manutenzione-orologi#impermeabilita\" target=\"_blank\" rel=\"noopener\"><em><span style=\"color: #b4946b;\">Leggi tutto<\/span><\/em><\/a><\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-100-5\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-style panel-row-style-for-100-5\" data-stretch-type=\"full\" ><div id=\"pgc-100-5-0\"  class=\"panel-grid-cell\" ><div id=\"panel-100-5-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"10\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h1><\/h1>\n<h1><a id=\"preventivi\"><\/a><span style=\"color: #ffffff;\">PREVENTIVI<\/span><\/h1>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\">Per una\u00a0diagnosi del vostro orologio con preventivo gratuito, potete venire nel <a href=\"https:\/\/watch-center.eu\/contatti#dove\" target=\"_blank\" rel=\"noopener\">nostro laboratorio<\/a> oppure richiederci un appuntamento presso il vostro domicilio ( Sicilia Occidentale ) o, in alternativa, potete inviarci l'orologio, dopo aver compilato il <a href=\"#modulo\">modulo sottostante<\/a>,\u00a0 tramite il Corriere delle Poste Italiane con il quale disponiamo di un\u00a0accordo in convenzione.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\">Siamo lieti di rispondere anche tramite <span style=\"color: #b4946b;\"><i class=\"fa fa-whatsapp \" ><\/i><\/span>\u00a0\"<em>WhatsApp\"<\/em> (clicca icona in basso) e gli altri <a href=\"#social\">Social<\/a> dove \u00e8 possibile inviare foto ed immagini dell'oggetto per una migliore valutazione.<\/span><\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-100-5-1\"  class=\"panel-grid-cell\" ><div id=\"panel-100-5-1-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"11\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277-100\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img \n\tsrc=\"https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/orologio-sfondo-scuro.jpg\" width=\"1296\" height=\"864\" srcset=\"https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/orologio-sfondo-scuro.jpg 1296w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/orologio-sfondo-scuro-300x200.jpg 300w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/orologio-sfondo-scuro-768x512.jpg 768w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/orologio-sfondo-scuro-1024x683.jpg 1024w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/orologio-sfondo-scuro-600x400.jpg 600w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/orologio-sfondo-scuro-272x182.jpg 272w\" sizes=\"(max-width: 1296px) 100vw, 1296px\" title=\"orologio sfondo scuro\" alt=\"orologio sfondo scuro\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-100-6\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-style panel-row-style-for-100-6\" data-stretch-type=\"full\" ><div id=\"pgc-100-6-0\"  class=\"panel-grid-cell\" ><div id=\"panel-100-6-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"12\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h1><a id=\"modulo\"><\/a>MODULO RICHIESTE<\/h1>\n<hr>\n<div class=\"wpforms-container \" id=\"wpforms-832\">\n<form id=\"wpforms-form-832\" class=\"wpforms-validate wpforms-form\" data-formid=\"832\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/100\" data-token=\"4a044cf7372a04c02ee27311ee1381a8\" data-token-time=\"1788335770\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><\/p>\n<div class=\"wpforms-field-container\">\n<div id=\"wpforms-832-field_9-container\" class=\"wpforms-field wpforms-field-select\" data-field-id=\"9\"><label class=\"wpforms-field-label\" for=\"wpforms-832-field_9\">Seleziona <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-832-field_9\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][9]\" required=\"required\"><option value=\"Privato\"  class=\"choice-1 depth-1\"  >Privato<\/option><option value=\"Azienda\"  class=\"choice-2 depth-1\"  >Azienda<\/option><option value=\"Ente Pubblico\"  class=\"choice-3 depth-1\"  >Ente Pubblico<\/option><option value=\"Ente Privato\"  class=\"choice-4 depth-1\"  >Ente Privato<\/option><\/select><\/div>\n<div id=\"wpforms-832-field_4-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-832-field_4\">Nome <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-832-field_4\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][4]\" placeholder=\"Cognome e nome\/Azienda o Ente\" required><\/div>\n<div id=\"wpforms-832-field_5-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-832-field_5\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-832-field_5\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][5]\" placeholder=\"inserire un e-mail valida\" spellcheck=\"false\" required><\/div>\n<div id=\"wpforms-832-field_3-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-832-field_3\">Telefono <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"number\" id=\"wpforms-832-field_3\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][3]\" placeholder=\"il vostro numero per essere ricontattati\" step=\"any\" required><\/div>\n<div id=\"wpforms-832-field_11-container\" class=\"wpforms-field wpforms-field-select\" data-field-id=\"11\"><label class=\"wpforms-field-label\" for=\"wpforms-832-field_11\">Orario<\/label><select id=\"wpforms-832-field_11\" class=\"wpforms-field-medium\" name=\"wpforms[fields][11]\"><option value=\"dalle ore 09:00 alle ore 11:00\"  selected='selected' class=\"choice-1 depth-1\"  >dalle ore 09:00 alle ore 11:00<\/option><option value=\"dalle ore 11:00 alle ore 13:00\"  class=\"choice-2 depth-1\"  >dalle ore 11:00 alle ore 13:00<\/option><option value=\"dalle ore 16:00 alle ore 18:00\"  class=\"choice-3 depth-1\"  >dalle ore 16:00 alle ore 18:00<\/option><option value=\"dalle ore 18:00 alle ore 20:00\"  class=\"choice-4 depth-1\"  >dalle ore 18:00 alle ore 20:00<\/option><\/select><\/div>\n<div id=\"wpforms-832-field_10-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-inline\" data-field-id=\"10\"><label class=\"wpforms-field-label\">Richiesta di: <span class=\"wpforms-required-label\">*<\/span><\/label><\/p>\n<ul id=\"wpforms-832-field_10\" class=\"wpforms-field-required\">\n<li class=\"choice-1 depth-1 wpforms-selected\"><input type=\"radio\" id=\"wpforms-832-field_10_1\" name=\"wpforms[fields][10]\" value=\"Informazioni\" required  checked='checked'><label class=\"wpforms-field-label-inline\" for=\"wpforms-832-field_10_1\">Informazioni<\/label><\/li>\n<li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-832-field_10_2\" name=\"wpforms[fields][10]\" value=\"Preventivo\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-832-field_10_2\">Preventivo<\/label><\/li>\n<li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-832-field_10_3\" name=\"wpforms[fields][10]\" value=\"Corriere a domicilio\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-832-field_10_3\">Corriere a domicilio<\/label><\/li>\n<\/ul>\n<\/div>\n<div id=\"wpforms-832-field_2-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-832-field_2\">Oggetto <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-832-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" placeholder=\"Es.: indicare marca e modello\" required><\/div>\n<div id=\"wpforms-832-field_8-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-832-field_8\">Messaggio <span class=\"wpforms-required-label\">*<\/span><\/label><textarea id=\"wpforms-832-field_8\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][8]\" required><\/textarea><\/div>\n<\/div>\n<p><!-- .wpforms-field-container --><\/p>\n<div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-v2\" >\n<div class=\"g-recaptcha\" data-sitekey=\"6LdUYWkUAAAAAE7qO0tWe-LPuNsdGrZTbrPb_6iV\"><\/div>\n<p><input type=\"text\" name=\"g-recaptcha-hidden\" class=\"wpforms-recaptcha-hidden\" style=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\" data-rule-recaptcha=\"1\"><\/div>\n<div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"832\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/watch-center.eu\/en\/wp-json\/wp\/v2\/pages\/100\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-832\" class=\"wpforms-submit\" data-alt-text=\"...sto inviando...\" data-submit-text=\"Invia\" aria-live=\"assertive\" value=\"wpforms-submit\">Invia<\/button><\/div>\n<\/form>\n<\/div>\n<p>  <!-- .wpforms-container --><\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-100-6-1\"  class=\"panel-grid-cell\" ><div id=\"panel-100-6-1-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"13\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h1><a id=\"aziende\"><\/a>ASSISTENZA PER LE AZIENDE<\/h1>\n<hr \/>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-923 aligncenter\" src=\"https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/assistenza-aziendale-300x166.jpg\" alt=\"assistenza aziendale\" width=\"565\" height=\"313\" srcset=\"https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/assistenza-aziendale-300x166.jpg 300w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/assistenza-aziendale-768x424.jpg 768w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/assistenza-aziendale.jpg 1024w, https:\/\/watch-center.eu\/wp-content\/uploads\/2018\/08\/assistenza-aziendale-600x331.jpg 600w\" sizes=\"auto, (max-width: 565px) 100vw, 565px\" \/><\/p>\n<p style=\"text-align: justify;\">Per i concessionari, gioiellerie, etc. Watch Center offre un servizio mirato per soddisfare le esigenze di logistica e mobilit\u00e0 dei clienti infatti, in tutta la Sicilia Occidentale e oltre, i nostri corrieri ( con cadenza settimanale o quindicinale ) ritirano le riparazioni di orologi a domicilio e li riconsegnano a fine lavori.<\/p>\n<p style=\"text-align: justify;\">Per richiedere il servizio gratuito \u00e8 sufficiente contattarci al nr. +39 091 586773 o compilando <a href=\"#modulo\">questo modulo<\/a>, oppure via <a href=\"mailto:info@watchcenterassistance.it\">email<\/a>, WhatsApp ed altri <a href=\"#social\">Social<\/a> e successivamente verremo presso la vostra sede per discutere i dettagli di collaborazione.<\/p>\n<p style=\"text-align: justify;\">Per il resto del territorio Italiano e per i privati provvediamo a ritirare e riconsegnare le riparazioni, tramite il Corriere delle Poste Italiane o TNT con il quale disponiamo di un accordo in convenzione.<a id=\"social\"><\/a><\/p>\n<hr \/>\n<p style=\"text-align: justify;\">\n<\/div>\n<\/div><\/div><div id=\"panel-100-6-1-1\" class=\"so-panel widget widget_sow-social-media-buttons panel-last-child\" data-index=\"14\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-social-media-buttons so-widget-sow-social-media-buttons-atom-901f8f41dba6-100\"\n\t\t\t\n\t\t>\n\n<div class=\"social-media-button-container\">\n\t\n\t\t<a \n\t\tclass=\"ow-button-hover sow-social-media-button-facebook-0 sow-social-media-button\" title=\"WATCH CENTER on Facebook\" aria-label=\"WATCH CENTER on Facebook\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.facebook.com\/watchcenterassistance\/\" \t\t>\n\t\t\t<span>\n\t\t\t\t\t\t\t\t<span class=\"sow-icon-fontawesome sow-fab\" data-sow-icon=\"&#xf39e;\"\n\t\t \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t\t\t\t<\/span>\n\t\t<\/a>\n\t\n\t\t<a \n\t\tclass=\"ow-button-hover sow-social-media-button-x-twitter-0 sow-social-media-button\" title=\"WATCH CENTER on X Twitter\" aria-label=\"WATCH CENTER on X Twitter\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/twitter.com\/watchcenterpa\" \t\t>\n\t\t\t<span>\n\t\t\t\t\t\t\t\t<span class=\"sow-icon-fontawesome sow-fab\" data-sow-icon=\"&#xe61b;\"\n\t\t \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t\t\t\t<\/span>\n\t\t<\/a>\n\t\n\t\t<a \n\t\tclass=\"ow-button-hover sow-social-media-button-google-0 sow-social-media-button\" title=\"WATCH CENTER on Google\" aria-label=\"WATCH CENTER on Google\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/plus.google.com\/111696499138555658715\" \t\t>\n\t\t\t<span>\n\t\t\t\t\t\t\t\t<span class=\"sow-icon-fontawesome sow-fab\" data-sow-icon=\"&#xf1a0;\"\n\t\t \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t\t\t\t<\/span>\n\t\t<\/a>\n\t\n\t\t<a \n\t\tclass=\"ow-button-hover sow-social-media-button-instagram-0 sow-social-media-button\" title=\"WATCH CENTER on Instagram\" aria-label=\"WATCH CENTER on Instagram\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.instagram.com\/watchcenterassistance\/\" \t\t>\n\t\t\t<span>\n\t\t\t\t\t\t\t\t<span class=\"sow-icon-fontawesome sow-fab\" data-sow-icon=\"&#xf16d;\"\n\t\t \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t\t\t\t<\/span>\n\t\t<\/a>\n\t\n\t\t<a \n\t\tclass=\"ow-button-hover sow-social-media-button-linkedin-0 sow-social-media-button\" title=\"WATCH CENTER on Linkedin\" aria-label=\"WATCH CENTER on Linkedin\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.linkedin.com\/in\/watchcenterpalermo\/\" \t\t>\n\t\t\t<span>\n\t\t\t\t\t\t\t\t<span class=\"sow-icon-fontawesome sow-fab\" data-sow-icon=\"&#xf0e1;\"\n\t\t \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t\t\t\t<\/span>\n\t\t<\/a>\n\t\n\t\t<a \n\t\tclass=\"ow-button-hover sow-social-media-button-pinterest-0 sow-social-media-button\" title=\"WATCH CENTER on Pinterest\" aria-label=\"WATCH CENTER on Pinterest\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.pinterest.it\/watchcenterpa\/\" \t\t>\n\t\t\t<span>\n\t\t\t\t\t\t\t\t<span class=\"sow-icon-fontawesome sow-fab\" data-sow-icon=\"&#xf0d2;\"\n\t\t \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t\t\t\t<\/span>\n\t\t<\/a>\n\t\n\t\t<a \n\t\tclass=\"ow-button-hover sow-social-media-button-youtube-0 sow-social-media-button\" title=\"WATCH CENTER on Youtube\" aria-label=\"WATCH CENTER on Youtube\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.youtube.com\/channel\/UCTHaBCY3hQEFaUfUOkL5hSg\" \t\t>\n\t\t\t<span>\n\t\t\t\t\t\t\t\t<span class=\"sow-icon-fontawesome sow-fab\" data-sow-icon=\"&#xf167;\"\n\t\t \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t\t\t\t<\/span>\n\t\t<\/a>\n\t\n\t\t<a \n\t\tclass=\"ow-button-hover sow-social-media-button-envelope-0 sow-social-media-button\" title=\"WATCH CENTER on Envelope\" aria-label=\"WATCH CENTER on Envelope\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"mailto:info@watchcenterassistance.it\" \t\t>\n\t\t\t<span>\n\t\t\t\t\t\t\t\t<span class=\"sow-icon-fontawesome sow-fas\" data-sow-icon=\"&#xf0e0;\"\n\t\t \n\t\taria-hidden=\"true\"><\/span>\t\t\t\t\t\t\t<\/span>\n\t\t<\/a>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>SERVIZI DI ASSISTENZA E RIPARAZIONE OROLOGI &#8221; L&#8217;orologio, non solo uno strumento di misura del tempo ma un gioiello che coniuga l\u2019eleganza di una marca di grande tradizione a prestazioni d\u2019alta tecnologia. Un bene cosi prezioso merita la necessaria cura esclusivamente nei centri specializzati per una idonea assistenza tecnica. Questo perch\u00e9 le dovute attenzioni possono essere poste solo da chi ha scelto questa professione investendo la propria passione nello studio, nell&#8217;aggiornamento continuo e nel miglioramento delle attrezzature adottando le adeguate tecnologie &#8221; CHI SIAMO Watch Center \u00e8 una azienda artigianale che effettua Servizi di assistenza tecnica, revisione, manutenzione, riparazione e restauro, di ogni tipo di orologio, da quelli da polso&hellip; <a class=\"read-more\" href=\"https:\/\/watch-center.eu\/en\/servizi-orologi\">Read More<\/a><\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-100","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/watch-center.eu\/en\/wp-json\/wp\/v2\/pages\/100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/watch-center.eu\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/watch-center.eu\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/watch-center.eu\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/watch-center.eu\/en\/wp-json\/wp\/v2\/comments?post=100"}],"version-history":[{"count":3,"href":"https:\/\/watch-center.eu\/en\/wp-json\/wp\/v2\/pages\/100\/revisions"}],"predecessor-version":[{"id":2622,"href":"https:\/\/watch-center.eu\/en\/wp-json\/wp\/v2\/pages\/100\/revisions\/2622"}],"wp:attachment":[{"href":"https:\/\/watch-center.eu\/en\/wp-json\/wp\/v2\/media?parent=100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}